

{"id":37756,"date":"2023-12-20T03:39:54","date_gmt":"2023-12-20T00:39:54","guid":{"rendered":"https:\/\/stage.deutschland-nederland.eu\/projects\/imagination\/"},"modified":"2026-05-13T07:51:45","modified_gmt":"2026-05-13T06:51:45","slug":"imagination","status":"publish","type":"projects","link":"https:\/\/deutschland-nederland.eu\/de\/projects\/imagination\/","title":{"rendered":"IMAGINATION"},"content":{"rendered":"<p>Der Begriff &#8222;Gliome&#8220; bezieht sich auf eine<br \/>\nSammelbezeichnung f&uuml;r verschiedene b&ouml;sartige Hirntumore. Wir klassifizieren<br \/>\nGliome anhand molekularer Merkmale, da diese Merkmale mit der &Uuml;berlebensrate<br \/>\nder Patienten in Verbindung stehen, die sterk variieren kann. Die<br \/>\nUnterscheidung der verschiedenen Gliomtypen ist daher von gro&szlig;er Bedeutung.<br \/>\nFr&uuml;here wissenschaftliche Ver&ouml;ffentlichungen haben jedoch gezeigt, dass eine<br \/>\nfortschrittliche Analyse der radiologischen Bildgebung, oft<br \/>\nMagnetresonanztomographie (MRT) genannt, den Tumor charakterisieren kann, ohne<br \/>\ndass der Patient sich einer Hirnbiopsie unterziehen muss. Diese nicht-invasive<br \/>\nTumorcharakterisierung erfolgt mithilfe k&uuml;nstlicher Intelligenz (KI), f&uuml;r die<br \/>\neine gro&szlig;e Anzahl von F&auml;llen verf&uuml;gbar sein muss. Mit Hilfe einer<br \/>\nmultizentrischen Datenbank, die aus einem Kleinprojekt im Rahmen des<br \/>\nGesamtprojekts entstanden ist und kontinuierlich mit neuen F&auml;llen aus den drei<br \/>\nkooperierenden Zentren erg&auml;nzt wird, k&ouml;nnen diese KI-Softwarepakete verwendet<br \/>\nwerden. Es ist jedoch unbekannt, inwieweit diese kostspieligen Pakete<br \/>\nAuswirkungen auf den Krankheitsverlauf und die Behandlung des Patienten haben.<br \/>\nDieses Projekt zielt darauf ab, den Einsatz von KI-Analysen auf MRT-Daten von<br \/>\nGliompatienten kritisch zu betrachten und in unserer Kooperationsregion zu<br \/>\nstandardisieren. Innerhalb dieses Projekts arbeiten wir daher mit Patienten,<br \/>\nverschiedenen klinischen &Auml;rzten und Wissenschaftlern unterschiedlicher<br \/>\nHintergr&uuml;nde zusammen. Durch grenz&uuml;berschreitende Zusammenarbeit erreichen wir<br \/>\neine gr&ouml;&szlig;ere und vielf&auml;ltigere Datensammlung einer seltenen Krankheit. Dadurch<br \/>\noptimieren wir die Repr&auml;sentativit&auml;t und Generalisierbarkeit der Ergebnisse,<br \/>\nwas zu einem besseren Verst&auml;ndnis der radiologischen Versorgung von<br \/>\nGliompatienten auf internationaler Ebene f&uuml;hrt. Das Zusammenf&uuml;hren von<br \/>\nSpezialisten innerhalb der Grenzregion wird auch zu innovativen Ans&auml;tzen, neuen<br \/>\nErkenntnissen und verbesserten Methodologien f&uuml;hren.<\/p>\n","protected":false},"parent":0,"template":"","pr-category":[271],"pr-priority":[285],"pr-stat":[253],"class_list":["post-37756","projects","type-projects","status-publish","hentry","pr-category-health-care-2","pr-priority-samenwerken-aan-een-verbonden-grensgebied","pr-stat-nieuw"],"acf":[],"_links":{"self":[{"href":"https:\/\/deutschland-nederland.eu\/de\/wp-json\/wp\/v2\/projects\/37756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/deutschland-nederland.eu\/de\/wp-json\/wp\/v2\/projects"}],"about":[{"href":"https:\/\/deutschland-nederland.eu\/de\/wp-json\/wp\/v2\/types\/projects"}],"wp:attachment":[{"href":"https:\/\/deutschland-nederland.eu\/de\/wp-json\/wp\/v2\/media?parent=37756"}],"wp:term":[{"taxonomy":"pr-category","embeddable":true,"href":"https:\/\/deutschland-nederland.eu\/de\/wp-json\/wp\/v2\/pr-category?post=37756"},{"taxonomy":"pr-priority","embeddable":true,"href":"https:\/\/deutschland-nederland.eu\/de\/wp-json\/wp\/v2\/pr-priority?post=37756"},{"taxonomy":"pr-stat","embeddable":true,"href":"https:\/\/deutschland-nederland.eu\/de\/wp-json\/wp\/v2\/pr-stat?post=37756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}